{"id":635,"count":1,"description":"","link":"https:\/\/blog.uantwerpen.be\/pintra-en\/tag\/social-servcie\/","name":"social servcie","slug":"social-servcie","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>social servcie Archives - Pintra (EN) Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.uantwerpen.be\/pintra-en\/tag\/social-servcie\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"social servcie Archives - Pintra (EN) Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.uantwerpen.be\/pintra-en\/tag\/social-servcie\/\" \/>\n<meta property=\"og:site_name\" content=\"Pintra (EN) Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.uantwerpen.be\\\/pintra-en\\\/tag\\\/social-servcie\\\/\",\"url\":\"https:\\\/\\\/blog.uantwerpen.be\\\/pintra-en\\\/tag\\\/social-servcie\\\/\",\"name\":\"social servcie Archives - Pintra (EN) Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.uantwerpen.be\\\/pintra-en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.uantwerpen.be\\\/pintra-en\\\/tag\\\/social-servcie\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.uantwerpen.be\\\/pintra-en\\\/tag\\\/social-servcie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.uantwerpen.be\\\/pintra-en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"social servcie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.uantwerpen.be\\\/pintra-en\\\/#website\",\"url\":\"https:\\\/\\\/blog.uantwerpen.be\\\/pintra-en\\\/\",\"name\":\"Pintra (EN) Blog\",\"description\":\"Pintra (EN) Blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.uantwerpen.be\\\/pintra-en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.uantwerpen.be\\\/pintra-en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.uantwerpen.be\\\/pintra-en\\\/#organization\",\"name\":\"Pintra (EN) Blog\",\"url\":\"https:\\\/\\\/blog.uantwerpen.be\\\/pintra-en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/blog.uantwerpen.be\\\/pintra-en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.uantwerpen.be\\\/pintra-en\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-UA-hor-1-en-neg-rgb.png\",\"contentUrl\":\"https:\\\/\\\/blog.uantwerpen.be\\\/pintra-en\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-UA-hor-1-en-neg-rgb.png\",\"width\":846,\"height\":250,\"caption\":\"Pintra (EN) Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.uantwerpen.be\\\/pintra-en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"social servcie Archives - Pintra (EN) Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.uantwerpen.be\/pintra-en\/tag\/social-servcie\/","og_locale":"en_GB","og_type":"article","og_title":"social servcie Archives - Pintra (EN) Blog","og_url":"https:\/\/blog.uantwerpen.be\/pintra-en\/tag\/social-servcie\/","og_site_name":"Pintra (EN) Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.uantwerpen.be\/pintra-en\/tag\/social-servcie\/","url":"https:\/\/blog.uantwerpen.be\/pintra-en\/tag\/social-servcie\/","name":"social servcie Archives - Pintra (EN) Blog","isPartOf":{"@id":"https:\/\/blog.uantwerpen.be\/pintra-en\/#website"},"breadcrumb":{"@id":"https:\/\/blog.uantwerpen.be\/pintra-en\/tag\/social-servcie\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.uantwerpen.be\/pintra-en\/tag\/social-servcie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.uantwerpen.be\/pintra-en\/"},{"@type":"ListItem","position":2,"name":"social servcie"}]},{"@type":"WebSite","@id":"https:\/\/blog.uantwerpen.be\/pintra-en\/#website","url":"https:\/\/blog.uantwerpen.be\/pintra-en\/","name":"Pintra (EN) Blog","description":"Pintra (EN) Blog","publisher":{"@id":"https:\/\/blog.uantwerpen.be\/pintra-en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.uantwerpen.be\/pintra-en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/blog.uantwerpen.be\/pintra-en\/#organization","name":"Pintra (EN) Blog","url":"https:\/\/blog.uantwerpen.be\/pintra-en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/blog.uantwerpen.be\/pintra-en\/#\/schema\/logo\/image\/","url":"https:\/\/blog.uantwerpen.be\/pintra-en\/wp-content\/uploads\/2023\/07\/cropped-UA-hor-1-en-neg-rgb.png","contentUrl":"https:\/\/blog.uantwerpen.be\/pintra-en\/wp-content\/uploads\/2023\/07\/cropped-UA-hor-1-en-neg-rgb.png","width":846,"height":250,"caption":"Pintra (EN) Blog"},"image":{"@id":"https:\/\/blog.uantwerpen.be\/pintra-en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/blog.uantwerpen.be\/pintra-en\/wp-json\/wp\/v2\/tags\/635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.uantwerpen.be\/pintra-en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.uantwerpen.be\/pintra-en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.uantwerpen.be\/pintra-en\/wp-json\/wp\/v2\/posts?tags=635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}