{"id":369,"count":1,"description":"","link":"https:\/\/blog.uantwerpen.be\/bladspiegel\/tag\/teun-van-son\/","name":"Teun van Son","slug":"teun-van-son","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Teun van Son Archives - bladspiegel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.uantwerpen.be\/bladspiegel\/tag\/teun-van-son\/\" \/>\n<meta property=\"og:locale\" content=\"nl_BE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teun van Son Archives - bladspiegel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.uantwerpen.be\/bladspiegel\/tag\/teun-van-son\/\" \/>\n<meta property=\"og:site_name\" content=\"bladspiegel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.uantwerpen.be\\\/bladspiegel\\\/tag\\\/teun-van-son\\\/\",\"url\":\"https:\\\/\\\/blog.uantwerpen.be\\\/bladspiegel\\\/tag\\\/teun-van-son\\\/\",\"name\":\"Teun van Son Archives - bladspiegel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.uantwerpen.be\\\/bladspiegel\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.uantwerpen.be\\\/bladspiegel\\\/tag\\\/teun-van-son\\\/#breadcrumb\"},\"inLanguage\":\"nl-BE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.uantwerpen.be\\\/bladspiegel\\\/tag\\\/teun-van-son\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.uantwerpen.be\\\/bladspiegel\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Teun van Son\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.uantwerpen.be\\\/bladspiegel\\\/#website\",\"url\":\"https:\\\/\\\/blog.uantwerpen.be\\\/bladspiegel\\\/\",\"name\":\"bladspiegel\",\"description\":\"bladspiegel\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.uantwerpen.be\\\/bladspiegel\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.uantwerpen.be\\\/bladspiegel\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.uantwerpen.be\\\/bladspiegel\\\/#organization\",\"name\":\"bladspiegel\",\"url\":\"https:\\\/\\\/blog.uantwerpen.be\\\/bladspiegel\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-BE\",\"@id\":\"https:\\\/\\\/blog.uantwerpen.be\\\/bladspiegel\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.uantwerpen.be\\\/bladspiegel\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/cropped-lw-nl-white.png\",\"contentUrl\":\"https:\\\/\\\/blog.uantwerpen.be\\\/bladspiegel\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/cropped-lw-nl-white.png\",\"width\":995,\"height\":250,\"caption\":\"bladspiegel\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.uantwerpen.be\\\/bladspiegel\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Teun van Son Archives - bladspiegel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.uantwerpen.be\/bladspiegel\/tag\/teun-van-son\/","og_locale":"nl_BE","og_type":"article","og_title":"Teun van Son Archives - bladspiegel","og_url":"https:\/\/blog.uantwerpen.be\/bladspiegel\/tag\/teun-van-son\/","og_site_name":"bladspiegel","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.uantwerpen.be\/bladspiegel\/tag\/teun-van-son\/","url":"https:\/\/blog.uantwerpen.be\/bladspiegel\/tag\/teun-van-son\/","name":"Teun van Son Archives - bladspiegel","isPartOf":{"@id":"https:\/\/blog.uantwerpen.be\/bladspiegel\/#website"},"breadcrumb":{"@id":"https:\/\/blog.uantwerpen.be\/bladspiegel\/tag\/teun-van-son\/#breadcrumb"},"inLanguage":"nl-BE"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.uantwerpen.be\/bladspiegel\/tag\/teun-van-son\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.uantwerpen.be\/bladspiegel\/"},{"@type":"ListItem","position":2,"name":"Teun van Son"}]},{"@type":"WebSite","@id":"https:\/\/blog.uantwerpen.be\/bladspiegel\/#website","url":"https:\/\/blog.uantwerpen.be\/bladspiegel\/","name":"bladspiegel","description":"bladspiegel","publisher":{"@id":"https:\/\/blog.uantwerpen.be\/bladspiegel\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.uantwerpen.be\/bladspiegel\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-BE"},{"@type":"Organization","@id":"https:\/\/blog.uantwerpen.be\/bladspiegel\/#organization","name":"bladspiegel","url":"https:\/\/blog.uantwerpen.be\/bladspiegel\/","logo":{"@type":"ImageObject","inLanguage":"nl-BE","@id":"https:\/\/blog.uantwerpen.be\/bladspiegel\/#\/schema\/logo\/image\/","url":"https:\/\/blog.uantwerpen.be\/bladspiegel\/wp-content\/uploads\/2021\/04\/cropped-lw-nl-white.png","contentUrl":"https:\/\/blog.uantwerpen.be\/bladspiegel\/wp-content\/uploads\/2021\/04\/cropped-lw-nl-white.png","width":995,"height":250,"caption":"bladspiegel"},"image":{"@id":"https:\/\/blog.uantwerpen.be\/bladspiegel\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/blog.uantwerpen.be\/bladspiegel\/wp-json\/wp\/v2\/tags\/369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.uantwerpen.be\/bladspiegel\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.uantwerpen.be\/bladspiegel\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.uantwerpen.be\/bladspiegel\/wp-json\/wp\/v2\/posts?tags=369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}